{"id":70,"date":"2017-03-03T18:03:32","date_gmt":"2017-03-03T18:03:32","guid":{"rendered":"http:\/\/www.calvoscasas.com\/wordpress\/?p=70"},"modified":"2017-07-04T21:02:38","modified_gmt":"2017-07-04T21:02:38","slug":"een-bouwterrein-van-437-m2-in-de-douro-streek","status":"publish","type":"post","link":"https:\/\/www.calvoscasas.com\/pt\/een-bouwterrein-van-437-m2-in-de-douro-streek\/","title":{"rendered":"\u20ac 20.000 &#8211; ref. 635.512"},"content":{"rendered":"<p>Een bouwterrein van 437 m2 in de Douro streek.<\/p>\n<div id='gallery-1' class='gallery galleryid-70 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/1338069613_384880782_1-Fotos-de-Terrenos-no-Douro-Varias-areas-1-e1497522945138.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"70\" src=\"https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/1338069613_384880782_1-Fotos-de-Terrenos-no-Douro-Varias-areas-1-e1497522945138.jpg\" class=\"attachment-large size-large\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_7.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"68\" src=\"https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_7.jpg\" class=\"attachment-large size-large\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_10.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"68\" src=\"https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_10.jpg\" class=\"attachment-large size-large\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_2.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"68\" src=\"https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_2.jpg\" class=\"attachment-large size-large\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_3.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"68\" src=\"https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_3.jpg\" class=\"attachment-large size-large\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_4.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"68\" src=\"https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_4.jpg\" class=\"attachment-large size-large\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_5.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"68\" src=\"https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_5.jpg\" class=\"attachment-large size-large\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_6.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"68\" src=\"https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_6.jpg\" class=\"attachment-large size-large\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_8.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"68\" src=\"https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_8.jpg\" class=\"attachment-large size-large\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_9.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"68\" src=\"https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/s_1338069613_384880782_9.jpg\" class=\"attachment-large size-large\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Een bouwterrein van 437 m2 in de Douro streek.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-70","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u20ac 20.000 - ref. 635.512 - Calvos Casas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.calvoscasas.com\/en\/een-bouwterrein-van-437-m2-in-de-douro-streek\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u20ac 20.000 - ref. 635.512 - Calvos Casas\" \/>\n<meta property=\"og:description\" content=\"Een bouwterrein van 437 m2 in de Douro streek.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.calvoscasas.com\/en\/een-bouwterrein-van-437-m2-in-de-douro-streek\/\" \/>\n<meta property=\"og:site_name\" content=\"Calvos Casas\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-03T18:03:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-07-04T21:02:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/1338069613_384880782_1-Fotos-de-Terrenos-no-Douro-Varias-areas-1-e1497522945138.jpg\" \/>\n<meta name=\"author\" content=\"frank\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"frank\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.calvoscasas.com\\\/en\\\/een-bouwterrein-van-437-m2-in-de-douro-streek\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.calvoscasas.com\\\/en\\\/een-bouwterrein-van-437-m2-in-de-douro-streek\\\/\"},\"author\":{\"name\":\"frank\",\"@id\":\"https:\\\/\\\/www.calvoscasas.com\\\/#\\\/schema\\\/person\\\/9def7fee62d5936acf1b09361a2976f7\"},\"headline\":\"\u20ac 20.000 &#8211; ref. 635.512\",\"datePublished\":\"2017-03-03T18:03:32+00:00\",\"dateModified\":\"2017-07-04T21:02:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.calvoscasas.com\\\/en\\\/een-bouwterrein-van-437-m2-in-de-douro-streek\\\/\"},\"wordCount\":17,\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.calvoscasas.com\\\/en\\\/een-bouwterrein-van-437-m2-in-de-douro-streek\\\/\",\"url\":\"https:\\\/\\\/www.calvoscasas.com\\\/en\\\/een-bouwterrein-van-437-m2-in-de-douro-streek\\\/\",\"name\":\"\u20ac 20.000 - ref. 635.512 - Calvos Casas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.calvoscasas.com\\\/#website\"},\"datePublished\":\"2017-03-03T18:03:32+00:00\",\"dateModified\":\"2017-07-04T21:02:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.calvoscasas.com\\\/#\\\/schema\\\/person\\\/9def7fee62d5936acf1b09361a2976f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.calvoscasas.com\\\/en\\\/een-bouwterrein-van-437-m2-in-de-douro-streek\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.calvoscasas.com\\\/en\\\/een-bouwterrein-van-437-m2-in-de-douro-streek\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.calvoscasas.com\\\/en\\\/een-bouwterrein-van-437-m2-in-de-douro-streek\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.calvoscasas.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u20ac 20.000 &#8211; ref. 635.512\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.calvoscasas.com\\\/#website\",\"url\":\"https:\\\/\\\/www.calvoscasas.com\\\/\",\"name\":\"Calvos Casas\",\"description\":\"AMI 20736\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.calvoscasas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.calvoscasas.com\\\/#\\\/schema\\\/person\\\/9def7fee62d5936acf1b09361a2976f7\",\"name\":\"frank\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4e36d2eb941749c45f2aa92a982745c02d49afa235d36cc919943fe666d335d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4e36d2eb941749c45f2aa92a982745c02d49afa235d36cc919943fe666d335d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4e36d2eb941749c45f2aa92a982745c02d49afa235d36cc919943fe666d335d?s=96&d=mm&r=g\",\"caption\":\"frank\"},\"sameAs\":[\"calvos casas portugal\"],\"url\":\"https:\\\/\\\/www.calvoscasas.com\\\/pt\\\/author\\\/frank\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u20ac 20.000 - ref. 635.512 - Calvos Casas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.calvoscasas.com\/en\/een-bouwterrein-van-437-m2-in-de-douro-streek\/","og_locale":"pt_PT","og_type":"article","og_title":"\u20ac 20.000 - ref. 635.512 - Calvos Casas","og_description":"Een bouwterrein van 437 m2 in de Douro streek.","og_url":"https:\/\/www.calvoscasas.com\/en\/een-bouwterrein-van-437-m2-in-de-douro-streek\/","og_site_name":"Calvos Casas","article_published_time":"2017-03-03T18:03:32+00:00","article_modified_time":"2017-07-04T21:02:38+00:00","og_image":[{"url":"https:\/\/www.calvoscasas.com\/wp-content\/uploads\/2017\/03\/1338069613_384880782_1-Fotos-de-Terrenos-no-Douro-Varias-areas-1-e1497522945138.jpg","type":"","width":"","height":""}],"author":"frank","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"frank"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.calvoscasas.com\/en\/een-bouwterrein-van-437-m2-in-de-douro-streek\/#article","isPartOf":{"@id":"https:\/\/www.calvoscasas.com\/en\/een-bouwterrein-van-437-m2-in-de-douro-streek\/"},"author":{"name":"frank","@id":"https:\/\/www.calvoscasas.com\/#\/schema\/person\/9def7fee62d5936acf1b09361a2976f7"},"headline":"\u20ac 20.000 &#8211; ref. 635.512","datePublished":"2017-03-03T18:03:32+00:00","dateModified":"2017-07-04T21:02:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.calvoscasas.com\/en\/een-bouwterrein-van-437-m2-in-de-douro-streek\/"},"wordCount":17,"articleSection":["Uncategorized"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.calvoscasas.com\/en\/een-bouwterrein-van-437-m2-in-de-douro-streek\/","url":"https:\/\/www.calvoscasas.com\/en\/een-bouwterrein-van-437-m2-in-de-douro-streek\/","name":"\u20ac 20.000 - ref. 635.512 - Calvos Casas","isPartOf":{"@id":"https:\/\/www.calvoscasas.com\/#website"},"datePublished":"2017-03-03T18:03:32+00:00","dateModified":"2017-07-04T21:02:38+00:00","author":{"@id":"https:\/\/www.calvoscasas.com\/#\/schema\/person\/9def7fee62d5936acf1b09361a2976f7"},"breadcrumb":{"@id":"https:\/\/www.calvoscasas.com\/en\/een-bouwterrein-van-437-m2-in-de-douro-streek\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.calvoscasas.com\/en\/een-bouwterrein-van-437-m2-in-de-douro-streek\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.calvoscasas.com\/en\/een-bouwterrein-van-437-m2-in-de-douro-streek\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.calvoscasas.com\/"},{"@type":"ListItem","position":2,"name":"\u20ac 20.000 &#8211; ref. 635.512"}]},{"@type":"WebSite","@id":"https:\/\/www.calvoscasas.com\/#website","url":"https:\/\/www.calvoscasas.com\/","name":"Calvos Casas","description":"AMI 20736","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.calvoscasas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.calvoscasas.com\/#\/schema\/person\/9def7fee62d5936acf1b09361a2976f7","name":"frank","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/b4e36d2eb941749c45f2aa92a982745c02d49afa235d36cc919943fe666d335d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4e36d2eb941749c45f2aa92a982745c02d49afa235d36cc919943fe666d335d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4e36d2eb941749c45f2aa92a982745c02d49afa235d36cc919943fe666d335d?s=96&d=mm&r=g","caption":"frank"},"sameAs":["calvos casas portugal"],"url":"https:\/\/www.calvoscasas.com\/pt\/author\/frank\/"}]}},"_links":{"self":[{"href":"https:\/\/www.calvoscasas.com\/pt\/wp-json\/wp\/v2\/posts\/70","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.calvoscasas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.calvoscasas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.calvoscasas.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.calvoscasas.com\/pt\/wp-json\/wp\/v2\/comments?post=70"}],"version-history":[{"count":9,"href":"https:\/\/www.calvoscasas.com\/pt\/wp-json\/wp\/v2\/posts\/70\/revisions"}],"predecessor-version":[{"id":2412,"href":"https:\/\/www.calvoscasas.com\/pt\/wp-json\/wp\/v2\/posts\/70\/revisions\/2412"}],"wp:attachment":[{"href":"https:\/\/www.calvoscasas.com\/pt\/wp-json\/wp\/v2\/media?parent=70"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.calvoscasas.com\/pt\/wp-json\/wp\/v2\/categories?post=70"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.calvoscasas.com\/pt\/wp-json\/wp\/v2\/tags?post=70"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}